{"id":158709,"date":"2021-10-12T07:57:15","date_gmt":"2021-10-12T11:57:15","guid":{"rendered":"https:\/\/flsportscoast.com\/?p=158709"},"modified":"2022-09-14T14:08:17","modified_gmt":"2022-09-14T18:08:17","slug":"meetings-and-more-in-floridas-sports-coast","status":"publish","type":"post","link":"https:\/\/flsportscoast.com\/fr\/meetings-and-more-in-floridas-sports-coast\/","title":{"rendered":"R\u00e9unions et bien plus sur la c\u00f4te sportive de la Floride"},"content":{"rendered":"<p>Tout travail et aucun jeu font de Jack un gar\u00e7on ennuyeux. Et ne nous lancez m\u00eame pas sur Jill. C&#039;est pourquoi les participants diront que vous \u00eates sorti du parc en organisant votre prochaine r\u00e9union, conf\u00e9rence ou \u00e9v\u00e9nement sp\u00e9cial sur la Sports Coast de la Floride.<\/p>\n\n\n\n<p>Abritant un bon m\u00e9lange d&#039;affaires et de plaisir, le comt\u00e9 de Pasco, en Floride, comprend 65 emplacements de classe mondiale qui offrent des \u00e9quipements de premier ordre, de merveilleux exercices de teambuilding et de d\u00e9licieuses options de restauration.<\/p>\n\n\n\n<p>Votre groupe pourrait rester dans la salle de r\u00e9union, mais qui voudrait ? <a href=\"https:\/\/flsportscoast.com\/fr\/meetings\/\">La c\u00f4te sportive de la Floride<\/a> est un lieu o\u00f9 les r\u00e9unions sont cens\u00e9es \u00eatre amusantes. Les couches de congestion et de stress sont emport\u00e9es d\u00e8s l&#039;arriv\u00e9e des participants. Jouer sur les points forts de la destination donnera aux participants exactement ce qu&#039;ils <em>toujours<\/em> vouloir.<\/p>\n\n\n\n<p>Les affaires se feront ici, mais votre groupe verra que cela n&#039;a pas \u00e0 \u00eatre ennuyeux, loin de l\u00e0, en fait. Que votre groupe veuille prolonger son s\u00e9jour pour un vrai voyage bleisure ou qu&#039;il soit simplement en ville pour votre \u00e9v\u00e9nement, les occasions ne manquent pas pour faire sensation.<\/p>\n\n\n\n<p>Des h\u00f4tels spectaculaires avec de vastes espaces de r\u00e9union aux lieux que vous pourriez autrement ignorer parce qu&#039;ils sont <em>trop amusant<\/em>, la Sports Coast de Floride vous ouvrira les yeux sur une nouvelle fa\u00e7on de voyager pour affaires. Que les jeux commencent. Laisse nous te montrer comment.<\/p>\n\n\n\n<h2 class=\"is-style-business_header has-dark-blue-color has-text-color wp-block-heading\" id=\"places-to-stay-and-play-1\">Endroits o\u00f9 s\u00e9journer et jouer<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"665\" src=\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/saddlebrook-resort-1-1024x665-1.jpeg\" alt=\"\" class=\"wp-image-227860\" srcset=\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/saddlebrook-resort-1-1024x665-1.jpeg 1024w, https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/saddlebrook-resort-1-1024x665-1-300x195.jpeg 300w, https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/saddlebrook-resort-1-1024x665-1-768x499.jpeg 768w, https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/saddlebrook-resort-1-1024x665-1-18x12.jpeg 18w, https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/saddlebrook-resort-1-1024x665-1-400x260.jpeg 400w, https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/saddlebrook-resort-1-1024x665-1-600x390.jpeg 600w, https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/saddlebrook-resort-1-1024x665-1-924x600.jpeg 924w, https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/saddlebrook-resort-1-1024x665-1-250x162.jpeg 250w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Station de vacances de Saddlebrook<\/strong><\/p>\n\n\n\n<p>Situ\u00e9 \u00e0 proximit\u00e9 de l&#039;Interstate 75, \u00e0 seulement 21 km des Tampa Premium Outlets et des boutiques de Wiregrass, le Saddlebrook Resort prim\u00e9 abrite deux parcours de golf Arnold Palmer Signature, 45 courts de tennis et 540 chambres r\u00e9cemment r\u00e9nov\u00e9es. Vos participants trouveront tout ce dont ils ont besoin, des salles de conf\u00e9rence ultramodernes aux 480 acres de terrain de loisirs \u00e0 explorer, pour leur \u00e9v\u00e9nement et leur h\u00e9bergement \u00e0 l&#039;h\u00f4tel. Les planificateurs appr\u00e9cieront les 95 000 pieds carr\u00e9s d&#039;espace de r\u00e9union, dont 34 salles de r\u00e9union et 15 sites ext\u00e9rieurs uniques. Des repas \u00e0 th\u00e8me aux offres audiovisuelles en passant par les services de transport, ce complexe rend les \u00e9v\u00e9nements comme un jeu d&#039;enfant (presque), que vous planifiez une r\u00e9union du conseil d&#039;administration de 10 personnes ou un gala\/rassemblement pour plus de 1 000 personnes.<\/p>\n\n\n\n<p>Si vos invit\u00e9s recherchent une nouvelle exp\u00e9rience, le Saddlebrook Resort est \u00e0 seulement 25 miles de Skydive City, un site de saut en parachute de classe mondiale \u00e0 Zephyrhills.<\/p>\n\n\n\n<p><strong>Hilton Garden Inn Tampa \u2013 Chapelle Wesley<\/strong><\/p>\n\n\n\n<p>Situ\u00e9 dans une magnifique r\u00e9serve naturelle, \u00e0 seulement 3,2 km des boutiques de Wiregrass, le Hilton Garden Inn Wesley Chapel offre l&#039;emplacement id\u00e9al pour tout voyage d&#039;affaires et\/ou de loisirs. Il y a six espaces \u00e9v\u00e9nementiels sur place, offrant une flexibilit\u00e9 pour une r\u00e9union intime de la suite C jusqu&#039;\u00e0 un rassemblement de groupe de taille moyenne.<\/p>\n\n\n\n<h2 class=\"is-style-business_header has-dark-blue-color has-text-color wp-block-heading\" id=\"bleisure-that-suits-you\">Le plaisir qui vous ressemble<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/a496be04-4845-4a94-803d-faac0bcbd259-1024x576-1.jpeg\" alt=\"\" class=\"wp-image-227862\" srcset=\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/a496be04-4845-4a94-803d-faac0bcbd259-1024x576-1.jpeg 1024w, https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/a496be04-4845-4a94-803d-faac0bcbd259-1024x576-1-300x169.jpeg 300w, https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/a496be04-4845-4a94-803d-faac0bcbd259-1024x576-1-768x432.jpeg 768w, https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/a496be04-4845-4a94-803d-faac0bcbd259-1024x576-1-18x10.jpeg 18w, https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/a496be04-4845-4a94-803d-faac0bcbd259-1024x576-1-400x225.jpeg 400w, https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/a496be04-4845-4a94-803d-faac0bcbd259-1024x576-1-600x338.jpeg 600w, https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/06\/a496be04-4845-4a94-803d-faac0bcbd259-1024x576-1-250x141.jpeg 250w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Lagon d&#039;Epperson<\/strong><\/p>\n\n\n\n<p>Le premier Crystal Lagoon du pays est une oasis de 7 acres loin de la salle de conf\u00e9rence. Les bars dans la piscine, les jeux de pelouse et le volley-ball de plage peuvent \u00eatre des choses que vous associez aux vacances, mais ils ne doivent pas \u00eatre aussi limit\u00e9s. Louez des espaces pouvant accueillir jusqu&#039;\u00e0 300 participants pour une pause dans l&#039;action de la r\u00e9union. Rien de tel que le r\u00e9seautage et la consolidation d&#039;\u00e9quipe comme une journ\u00e9e au paradis.<\/p>\n\n\n\n<p><strong>\u00c9v\u00e9nement principal<\/strong><\/p>\n\n\n\n<p>Si vous recherchez un v\u00e9ritable terrain de jeu pour adultes pour une r\u00e9ception d\u00e9contract\u00e9e ou des opportunit\u00e9s de teambuilding, ne cherchez pas plus loin. Les jeux sur ce site de Wesley Chapel incluent le jeu laser, le bowling, le billard, l&#039;escalade, le mini-golf, les stations de r\u00e9alit\u00e9 virtuelle et bien plus encore. Vous pouvez acheter tout le b\u00e2timent ou choisir votre emplacement et votre activit\u00e9. Et oui, il y a m\u00eame un espace de r\u00e9union si vous cherchez \u00e0 changer de d\u00e9cor par rapport \u00e0 un lieu traditionnel.<\/p>\n\n\n\n<p><strong>Centre de tennis et de bien-\u00eatre Sarah Vande Berg<\/strong><\/p>\n\n\n\n<p>Ce site au c\u0153ur de Zephyrhills est id\u00e9al pour un vrai R&amp;R. Les tournois de tennis et de pickleball constituent de formidables loisirs. Les participants peuvent se d\u00e9tendre en profitant de la cryoth\u00e9rapie, de la salle de sel, du sauna, des conseils sportifs, du centre de fitness et du restaurant sur place. Parlez d&#039;un r\u00e9gal pour le corps et l&#039;esprit.<\/p>\n\n\n\n<p><strong>Location de kayak Salty Dog<\/strong><\/p>\n\n\n\n<p>Demandez \u00e0 votre \u00e9quipe de trouver le bon coup pour r\u00e9ussir avec un exercice de teambuilding sur l&#039;eau. Situ\u00e9 \u00e0 l&#039;int\u00e9rieur du parc d&#039;\u00c9tat de Werner-Boyce Salt Springs, Salty Dog propose des \u00e9co-visites de deux heures pour explorer la beaut\u00e9 naturelle de la r\u00e9gion. Apprenez-en davantage sur les sources sal\u00e9es et la diversit\u00e9 du syst\u00e8me de flore et de faune et appliquez ces le\u00e7ons pour pr\u00e9server le succ\u00e8s de votre entreprise \u00e0 long terme.<\/p>\n\n\n\n<p><strong>AdventHealth Center Glace<\/strong><\/p>\n\n\n\n<p>Les sports nautiques viennent \u00e0 l&#039;esprit quand on pense \u00e0 la Floride. N&#039;oubliez pas que la glace est de l&#039;eau gel\u00e9e et peut \u00eatre beaucoup plus froide sur une surface sur laquelle jouer. Le curling et le ballon-balai ne sont que deux des options que les planificateurs ont dans leur livre de jeu pour un apr\u00e8s-midi ou une soir\u00e9e amusante \u00e0 l&#039;ext\u00e9rieur de l&#039;h\u00f4tel. Une salle polyvalente vient de s&#039;ajouter \u00e0 ce 150 000 pi.ca. abrite cinq patinoires de classe mondiale, qui peuvent \u00eatre converties en espaces \u00e9v\u00e9nementiels pouvant accueillir jusqu&#039;\u00e0 3 000 participants.<\/p>\n\n\n\n<h2 class=\"is-style-business_header has-dark-blue-color has-text-color wp-block-heading\" id=\"work-hard-play-hard\">Arriver ici<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\" style=\"justify-content:center\">\n<div class=\"wp-block-column getting-here-is-easy-map-wrap is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:90%\"><div class=\"stylizedHeaderBlock h3 has-text-align-center\"><div class=\"stylizedHeaderBlockContent noSwash\">\n<h3 class=\"has-text-align-center is-style-stylized_no_swash has-orange-color has-text-color wp-block-heading\" id=\"getting-here-is-easy-1\">Arriver ici<br>est facile<\/h3>\n<div class=\"image blueArrowNoSwash\"><img decoding=\"async\" src=\"https:\/\/flsportscoast.com\/wp-content\/themes\/mm-nino-theme\/assets\/images\/icons\/art-arrow-blue.svg\"\/><\/div><\/div><\/div>\n\n\n<figure class=\"wp-block-image size-full getting-here-is-easy-map\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"602\" src=\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/07\/getting-to-floridas-sports-coast.gif\" alt=\"\" class=\"wp-image-228684\"\/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Il ne serait pas juste de travailler dur pour atteindre une destination o\u00f9 il est facile de jouer. Situ\u00e9 sur la c\u00f4te ouest de la Floride, \u00e0 seulement 30 minutes de l&#039;a\u00e9roport international de Tampa, Florida&#039;s Sports Coast offre \u00e0 ses clients un acc\u00e8s facile via des vols directs cl\u00e9s depuis les march\u00e9s \u00e0 travers le pays. Nous sommes \u00e9galement \u00e0 90 minutes d&#039;Orlando et des autoroutes telles que la I-75, l&#039;US 41 et la Suncoast Parkway relient New Port Richey, Dade City, Zephyrhills et Wesley Chapel.<\/p>\n\n\n\n<h2 class=\"is-style-business_header has-dark-blue-color has-text-color wp-block-heading\" id=\"work-hard-play-hard\">Travailler dur, jouer dur<\/h2>\n\n\n\n<p>Nous ne disons pas que les affaires ne sont pas importantes. N&#039;oubliez pas que le saignement des loisirs en peu de temps contribue grandement \u00e0 transformer un rassemblement banal en un \u00e9v\u00e9nement dont on se souviendra pendant des ann\u00e9es. La combinaison d&#039;espaces \u00e9v\u00e9nementiels uniques, d&#039;opportunit\u00e9s de teambuilding et d&#039;exp\u00e9riences pr\u00eates \u00e0 l&#039;emploi est ce que recherchent les participants d&#039;aujourd&#039;hui. Voyez par vous-m\u00eame pourquoi la Florida&#039;s Sports Coast est une proposition gagnante pour vous et votre organisation.<\/p>","protected":false},"excerpt":{"rendered":"<p>Tout travail et aucun jeu font de Jack un gar\u00e7on ennuyeux. Et ne nous lancez m\u00eame pas sur Jill.<\/p>","protected":false},"author":2,"featured_media":229002,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","footnotes":""},"categories":[233],"tags":[],"class_list":["post-158709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Meetings and More in Florida\u2019s Sports Coast | Florida&#039;s Sports Coast<\/title>\n<meta name=\"description\" content=\"All work and no play make Jack a dull boy. And don\u2019t even get us started on Jill. That\u2019s why attendees will say you\u2019ve hit it out of the park by bringing\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flsportscoast.com\/fr\/meetings-and-more-in-floridas-sports-coast\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meetings and More in Florida\u2019s Sports Coast | Florida&#039;s Sports Coast\" \/>\n<meta property=\"og:description\" content=\"All work and no play make Jack a dull boy. And don\u2019t even get us started on Jill. That\u2019s why attendees will say you\u2019ve hit it out of the park by bringing\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flsportscoast.com\/fr\/meetings-and-more-in-floridas-sports-coast\/\" \/>\n<meta property=\"og:site_name\" content=\"Florida&#039;s Sports Coast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FLSportsCoast\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-12T11:57:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-14T18:08:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2021\/10\/Meetings-and-More-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1346\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kolby Kucyk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FLSportsCoast\" \/>\n<meta name=\"twitter:site\" content=\"@FLSportsCoast\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kolby Kucyk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/\"},\"author\":{\"name\":\"Kolby Kucyk\",\"@id\":\"https:\/\/flsportscoast.com\/#\/schema\/person\/cfc3d284c4eee1a1fff07034c5321b8b\"},\"headline\":\"Meetings and More in Florida\u2019s Sports Coast\",\"datePublished\":\"2021-10-12T11:57:15+00:00\",\"dateModified\":\"2022-09-14T18:08:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/\"},\"wordCount\":929,\"publisher\":{\"@id\":\"https:\/\/flsportscoast.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2021\/10\/Meetings-and-More-scaled.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/\",\"url\":\"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/\",\"name\":\"Meetings and More in Florida\u2019s Sports Coast | Florida&#039;s Sports Coast\",\"isPartOf\":{\"@id\":\"https:\/\/flsportscoast.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2021\/10\/Meetings-and-More-scaled.jpg\",\"datePublished\":\"2021-10-12T11:57:15+00:00\",\"dateModified\":\"2022-09-14T18:08:17+00:00\",\"description\":\"All work and no play make Jack a dull boy. And don\u2019t even get us started on Jill. That\u2019s why attendees will say you\u2019ve hit it out of the park by bringing\",\"breadcrumb\":{\"@id\":\"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#primaryimage\",\"url\":\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2021\/10\/Meetings-and-More-scaled.jpg\",\"contentUrl\":\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2021\/10\/Meetings-and-More-scaled.jpg\",\"width\":1920,\"height\":1346},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/flsportscoast.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meetings and More in Florida\u2019s Sports Coast\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/flsportscoast.com\/#website\",\"url\":\"https:\/\/flsportscoast.com\/\",\"name\":\"Florida&#039;s Sports Coast\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/flsportscoast.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/flsportscoast.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/flsportscoast.com\/#organization\",\"name\":\"Florida Sports Coast\",\"url\":\"https:\/\/flsportscoast.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/flsportscoast.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/07\/fl-sports-coast-logo-color.png\",\"contentUrl\":\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/07\/fl-sports-coast-logo-color.png\",\"width\":1028,\"height\":1028,\"caption\":\"Florida Sports Coast\"},\"image\":{\"@id\":\"https:\/\/flsportscoast.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FLSportsCoast\/\",\"https:\/\/x.com\/FLSportsCoast\",\"https:\/\/www.pinterest.com\/FLSportsCoast\/\",\"https:\/\/www.instagram.com\/flsportscoast\/\",\"https:\/\/www.youtube.com\/channel\/UCJNh4zCnO3RPH6D9NPAoyGQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/flsportscoast.com\/#\/schema\/person\/cfc3d284c4eee1a1fff07034c5321b8b\",\"name\":\"Kolby Kucyk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/flsportscoast.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/aace94891bc3ac5399e821c65cfbeb69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/aace94891bc3ac5399e821c65cfbeb69?s=96&d=mm&r=g\",\"caption\":\"Kolby Kucyk\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9unions et bien plus sur la c\u00f4te sportive de la Floride | La c\u00f4te sportive de la Floride","description":"Tout travail et aucun jeu font de Jack un gar\u00e7on ennuyeux. Et ne nous lancez m\u00eame pas sur Jill. C&#039;est pourquoi les participants diront que vous \u00eates sorti du parc en apportant","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flsportscoast.com\/fr\/meetings-and-more-in-floridas-sports-coast\/","og_locale":"fr_FR","og_type":"article","og_title":"Meetings and More in Florida\u2019s Sports Coast | Florida&#039;s Sports Coast","og_description":"All work and no play make Jack a dull boy. And don\u2019t even get us started on Jill. That\u2019s why attendees will say you\u2019ve hit it out of the park by bringing","og_url":"https:\/\/flsportscoast.com\/fr\/meetings-and-more-in-floridas-sports-coast\/","og_site_name":"Florida&#039;s Sports Coast","article_publisher":"https:\/\/www.facebook.com\/FLSportsCoast\/","article_published_time":"2021-10-12T11:57:15+00:00","article_modified_time":"2022-09-14T18:08:17+00:00","og_image":[{"width":1920,"height":1346,"url":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2021\/10\/Meetings-and-More-scaled.jpg","type":"image\/jpeg"}],"author":"Kolby Kucyk","twitter_card":"summary_large_image","twitter_creator":"@FLSportsCoast","twitter_site":"@FLSportsCoast","twitter_misc":{"Written by":"Kolby Kucyk","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#article","isPartOf":{"@id":"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/"},"author":{"name":"Kolby Kucyk","@id":"https:\/\/flsportscoast.com\/#\/schema\/person\/cfc3d284c4eee1a1fff07034c5321b8b"},"headline":"Meetings and More in Florida\u2019s Sports Coast","datePublished":"2021-10-12T11:57:15+00:00","dateModified":"2022-09-14T18:08:17+00:00","mainEntityOfPage":{"@id":"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/"},"wordCount":929,"publisher":{"@id":"https:\/\/flsportscoast.com\/#organization"},"image":{"@id":"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#primaryimage"},"thumbnailUrl":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2021\/10\/Meetings-and-More-scaled.jpg","articleSection":["News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/","url":"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/","name":"R\u00e9unions et bien plus sur la c\u00f4te sportive de la Floride | La c\u00f4te sportive de la Floride","isPartOf":{"@id":"https:\/\/flsportscoast.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#primaryimage"},"image":{"@id":"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#primaryimage"},"thumbnailUrl":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2021\/10\/Meetings-and-More-scaled.jpg","datePublished":"2021-10-12T11:57:15+00:00","dateModified":"2022-09-14T18:08:17+00:00","description":"Tout travail et aucun jeu font de Jack un gar\u00e7on ennuyeux. Et ne nous lancez m\u00eame pas sur Jill. C&#039;est pourquoi les participants diront que vous \u00eates sorti du parc en apportant","breadcrumb":{"@id":"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#primaryimage","url":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2021\/10\/Meetings-and-More-scaled.jpg","contentUrl":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2021\/10\/Meetings-and-More-scaled.jpg","width":1920,"height":1346},{"@type":"BreadcrumbList","@id":"https:\/\/flsportscoast.com\/meetings-and-more-in-floridas-sports-coast\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/flsportscoast.com\/"},{"@type":"ListItem","position":2,"name":"Meetings and More in Florida\u2019s Sports Coast"}]},{"@type":"WebSite","@id":"https:\/\/flsportscoast.com\/#website","url":"https:\/\/flsportscoast.com\/","name":"La c\u00f4te sportive de la Floride","description":"","publisher":{"@id":"https:\/\/flsportscoast.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flsportscoast.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/flsportscoast.com\/#organization","name":"C\u00f4te sportive de la Floride","url":"https:\/\/flsportscoast.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/flsportscoast.com\/#\/schema\/logo\/image\/","url":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/07\/fl-sports-coast-logo-color.png","contentUrl":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/07\/fl-sports-coast-logo-color.png","width":1028,"height":1028,"caption":"Florida Sports Coast"},"image":{"@id":"https:\/\/flsportscoast.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FLSportsCoast\/","https:\/\/x.com\/FLSportsCoast","https:\/\/www.pinterest.com\/FLSportsCoast\/","https:\/\/www.instagram.com\/flsportscoast\/","https:\/\/www.youtube.com\/channel\/UCJNh4zCnO3RPH6D9NPAoyGQ"]},{"@type":"Person","@id":"https:\/\/flsportscoast.com\/#\/schema\/person\/cfc3d284c4eee1a1fff07034c5321b8b","name":"Kolby Kucyk","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/flsportscoast.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/aace94891bc3ac5399e821c65cfbeb69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aace94891bc3ac5399e821c65cfbeb69?s=96&d=mm&r=g","caption":"Kolby Kucyk"}}]}},"thumb_url":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2021\/10\/Meetings-and-More-250x175.jpg","_links":{"self":[{"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/posts\/158709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/comments?post=158709"}],"version-history":[{"count":12,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/posts\/158709\/revisions"}],"predecessor-version":[{"id":229872,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/posts\/158709\/revisions\/229872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/media\/229002"}],"wp:attachment":[{"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/media?parent=158709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/categories?post=158709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/tags?post=158709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}