{"id":100682,"date":"2020-12-14T12:31:27","date_gmt":"2020-12-14T17:31:27","guid":{"rendered":"https:\/\/flsportscoast.com\/?post_type=ajde_events&amp;p=100682"},"modified":"2020-12-14T12:31:27","modified_gmt":"2020-12-14T17:31:27","slug":"nova-era-live-performance","status":"publish","type":"ajde_events","link":"https:\/\/flsportscoast.com\/fr\/event\/nova-era-live-performance\/","title":{"rendered":"Performance en direct de l&#039;\u00e8re de la Nouvelle-\u00c9cosse"},"content":{"rendered":"<p>Profitez de la musique classique avec une touche moderne lors d&#039;une performance live de Nova Era au Pioneer Florida Museum &amp; Village.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-100683\" src=\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2020\/12\/Nova-Era-Live-Performance.jpg\" alt=\"\" width=\"837\" height=\"1086\" \/><\/p>","protected":false},"author":5,"featured_media":225998,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":""},"tags":[],"event_location":[189],"event_type":[],"event_type_2":[],"class_list":["post-100682","ajde_events","type-ajde_events","status-publish","has-post-thumbnail","hentry","event_location-pioneer-florida-museum-village"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nova Era Live Performance | Florida&#039;s Sports Coast<\/title>\n<meta name=\"description\" content=\"Enjoy classical music with a modern twist during a live performance by Nova Era at the Pioneer Florida Museum &amp; Village.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flsportscoast.com\/fr\/event\/nova-era-live-performance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nova Era Live Performance | Florida&#039;s Sports Coast\" \/>\n<meta property=\"og:description\" content=\"Enjoy classical music with a modern twist during a live performance by Nova Era at the Pioneer Florida Museum &amp; Village.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flsportscoast.com\/fr\/event\/nova-era-live-performance\/\" \/>\n<meta property=\"og:site_name\" content=\"Florida&#039;s Sports Coast\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FLSportsCoast\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2020\/12\/Grass-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FLSportsCoast\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/\",\"url\":\"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/\",\"name\":\"Nova Era Live Performance | Florida&#039;s Sports Coast\",\"isPartOf\":{\"@id\":\"https:\/\/flsportscoast.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2020\/12\/Grass-scaled.jpg\",\"datePublished\":\"2020-12-14T17:31:27+00:00\",\"dateModified\":\"2020-12-14T17:31:27+00:00\",\"description\":\"Enjoy classical music with a modern twist during a live performance by Nova Era at the Pioneer Florida Museum &amp; Village.\",\"breadcrumb\":{\"@id\":\"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/#primaryimage\",\"url\":\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2020\/12\/Grass-scaled.jpg\",\"contentUrl\":\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2020\/12\/Grass-scaled.jpg\",\"width\":1920,\"height\":1281},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/flsportscoast.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\/\/flsportscoast.com\/event\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nova Era Live Performance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/flsportscoast.com\/#website\",\"url\":\"https:\/\/flsportscoast.com\/\",\"name\":\"Florida&#039;s Sports Coast\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/flsportscoast.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/flsportscoast.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/flsportscoast.com\/#organization\",\"name\":\"Florida Sports Coast\",\"url\":\"https:\/\/flsportscoast.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/flsportscoast.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/07\/fl-sports-coast-logo-color.png\",\"contentUrl\":\"https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/07\/fl-sports-coast-logo-color.png\",\"width\":1028,\"height\":1028,\"caption\":\"Florida Sports Coast\"},\"image\":{\"@id\":\"https:\/\/flsportscoast.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FLSportsCoast\/\",\"https:\/\/x.com\/FLSportsCoast\",\"https:\/\/www.pinterest.com\/FLSportsCoast\/\",\"https:\/\/www.instagram.com\/flsportscoast\/\",\"https:\/\/www.youtube.com\/channel\/UCJNh4zCnO3RPH6D9NPAoyGQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Performance en direct de l&#039;\u00e8re Nova | La c\u00f4te sportive de la Floride","description":"Profitez de la musique classique avec une touche moderne lors d&#039;une performance live de Nova Era au Pioneer Florida Museum &amp; Village.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flsportscoast.com\/fr\/event\/nova-era-live-performance\/","og_locale":"fr_FR","og_type":"article","og_title":"Nova Era Live Performance | Florida&#039;s Sports Coast","og_description":"Enjoy classical music with a modern twist during a live performance by Nova Era at the Pioneer Florida Museum &amp; Village.","og_url":"https:\/\/flsportscoast.com\/fr\/event\/nova-era-live-performance\/","og_site_name":"Florida&#039;s Sports Coast","article_publisher":"https:\/\/www.facebook.com\/FLSportsCoast\/","og_image":[{"width":1920,"height":1281,"url":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2020\/12\/Grass-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@FLSportsCoast","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/","url":"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/","name":"Performance en direct de l&#039;\u00e8re Nova | La c\u00f4te sportive de la Floride","isPartOf":{"@id":"https:\/\/flsportscoast.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/#primaryimage"},"image":{"@id":"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/#primaryimage"},"thumbnailUrl":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2020\/12\/Grass-scaled.jpg","datePublished":"2020-12-14T17:31:27+00:00","dateModified":"2020-12-14T17:31:27+00:00","description":"Profitez de la musique classique avec une touche moderne lors d&#039;une performance live de Nova Era au Pioneer Florida Museum &amp; Village.","breadcrumb":{"@id":"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/#primaryimage","url":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2020\/12\/Grass-scaled.jpg","contentUrl":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2020\/12\/Grass-scaled.jpg","width":1920,"height":1281},{"@type":"BreadcrumbList","@id":"https:\/\/flsportscoast.com\/event\/nova-era-live-performance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/flsportscoast.com\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/flsportscoast.com\/event\/"},{"@type":"ListItem","position":3,"name":"Nova Era Live Performance"}]},{"@type":"WebSite","@id":"https:\/\/flsportscoast.com\/#website","url":"https:\/\/flsportscoast.com\/","name":"La c\u00f4te sportive de la Floride","description":"","publisher":{"@id":"https:\/\/flsportscoast.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flsportscoast.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/flsportscoast.com\/#organization","name":"C\u00f4te sportive de la Floride","url":"https:\/\/flsportscoast.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/flsportscoast.com\/#\/schema\/logo\/image\/","url":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/07\/fl-sports-coast-logo-color.png","contentUrl":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2022\/07\/fl-sports-coast-logo-color.png","width":1028,"height":1028,"caption":"Florida Sports Coast"},"image":{"@id":"https:\/\/flsportscoast.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FLSportsCoast\/","https:\/\/x.com\/FLSportsCoast","https:\/\/www.pinterest.com\/FLSportsCoast\/","https:\/\/www.instagram.com\/flsportscoast\/","https:\/\/www.youtube.com\/channel\/UCJNh4zCnO3RPH6D9NPAoyGQ"]}]}},"meta_fields":{"evcal_srow":"1612105200","evcal_erow":"1612116000","event_year":"2021","_edit_last":"3","_thumbnail_id":"225998","evcal_event_color":"ce3439","evcal_lmlink":"https:\/\/www.pioneerfloridamuseum.org\/index.php?option=com_content&view=article&id=152&Itemid=74","evcal_hide_locname":"no","evcal_gmap_gen":"no","evcal_name_over_img":"no","evo_access_control_location":"no","evcal_repeat":"no","_evcal_rep_series":"no","_evcal_rep_endt":"no","_evcal_rep_series_clickable":"no","evcal_rep_freq":"daily","evcal_rep_gap":"1","evcal_rep_num":"1","evp_repeat_rb":"dom","evo_repeat_wom":"1","evp_repeat_rb_wk":"sing","evcal_lmlink_target":"yes","_evcal_exlink_option":"1","evo_hide_endtime":"no","evo_span_hidden_end":"no","evo_year_long":"no","_evo_month_long":"no","evo_evcrd_field_org":"no","_edata":{"day_light":"no"},"_yoast_wpseo_content_score":"90","evcal_allday":"no","_event_month":"1","_featured":"no"},"addr":{"location_lon":null,"location_lat":null,"location_address":"15602 Pioneer Museum Road","location_city":"Dade City","location_state":"FL","location_country":"USA","evcal_location_link":"","evo_loc_img":""},"thumb_url":"https:\/\/flsportscoast.com\/wp-content\/uploads\/2020\/12\/Grass-250x167.jpg","_links":{"self":[{"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/ajde_events\/100682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/ajde_events"}],"about":[{"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/types\/ajde_events"}],"author":[{"embeddable":true,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/comments?post=100682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/media\/225998"}],"wp:attachment":[{"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/media?parent=100682"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/tags?post=100682"},{"taxonomy":"event_location","embeddable":true,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/event_location?post=100682"},{"taxonomy":"event_type","embeddable":true,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/event_type?post=100682"},{"taxonomy":"event_type_2","embeddable":true,"href":"https:\/\/flsportscoast.com\/fr\/wp-json\/wp\/v2\/event_type_2?post=100682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}